{"id":30854,"date":"2023-05-29T12:15:54","date_gmt":"2023-05-29T12:15:54","guid":{"rendered":"https:\/\/kalatrava79.com\/?page_id=30854"},"modified":"2023-08-04T08:12:02","modified_gmt":"2023-08-04T08:12:02","slug":"real-estate-surgeon","status":"publish","type":"page","link":"https:\/\/www.kalatrava79.com\/index.php\/real-estate-surgeon\/","title":{"rendered":"REAL ESTATE SURGEON"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693&#8243; background_image=&#8221;https:\/\/kalatrava79.com\/wp-content\/uploads\/2023\/06\/5.jpg&#8221; background_blend=&#8221;overlay&#8221; custom_padding=&#8221;10vw||10vw||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{%22gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693%22:%91%22background_color%22%93}&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Libre Baskerville||||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;75px&#8221; header_font_size_tablet=&#8221;50px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Kalatrava79.com<span>\u00a0<strong>Real Estate Surgeon<\/strong><\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22background_color%22%93}&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Libre Baskerville||||||||&#8221; text_text_color=&#8221;gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693&#8243; header_font=&#8221;Red Hat Text|700|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;38.8px&#8221; header_5_font=&#8221;Libre Baskerville|700|||||||&#8221; header_5_text_color=&#8221;gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693&#8243; header_5_font_size=&#8221;38.8px&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{%22gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693%22:%91%22header_5_text_color%22,%22text_text_color%22%93}&#8221;]<\/p>\n<section id=\"comp-ld8tdxun\" class=\"xuzjBY comp-ld8tdxun wixui-section\" data-testid=\"section-container\" tabindex=\"-1\">\n<div class=\"comp-ld8tdxun-container\" data-testid=\"responsive-container-content\">\n<div id=\"comp-ld8tdxvm\" class=\"BaOVQ8 tz5f0K comp-ld8tdxvm wixui-rich-text\" data-testid=\"richTextElement\">\n<h5 class=\"font_5 wixui-rich-text__text\">A Comprehensive Program<\/h5>\n<\/div>\n<\/div>\n<\/section>\n<div id=\"comp-ld8tn2wc\" class=\"QOX0dS JCRlLH comp-ld8tn2wc-container comp-ld8tn2wc wixui-box\">\n<div id=\"comp-ld8tn2wf\" class=\"BaOVQ8 tz5f0K comp-ld8tn2wf wixui-rich-text\" data-testid=\"richTextElement\">\n<p class=\"font_8 wixui-rich-text__text\">Here\u2019s what you will learn to achieve that goal<\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Online Consultation&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf03d;||fa||900&#8243; icon_color=&#8221;gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Libre Baskerville|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693&#8243; custom_padding=&#8221;3vw||3vw||true|false&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693&#8243; global_colors_info=&#8221;{%22gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693%22:%91%22icon_color%22,%22header_text_color%22,%22border_color_all%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;One to one&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf51c;||fa||900&#8243; icon_color=&#8221;gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Libre Baskerville|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693&#8243; custom_padding=&#8221;3vw||3vw||true|false&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693&#8243; global_colors_info=&#8221;{%22gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693%22:%91%22icon_color%22,%22header_text_color%22,%22border_color_all%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Experienced Mentor&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf508;||fa||900&#8243; icon_color=&#8221;gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Libre Baskerville|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693&#8243; custom_padding=&#8221;3vw||3vw||true|false&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693&#8243; global_colors_info=&#8221;{%22gcid-c1d661e2-ac59-477e-9b7a-4c286ea0b693%22:%91%22icon_color%22,%22header_text_color%22,%22border_color_all%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_5_font=&#8221;Libre Baskerville|700|||||||&#8221; header_5_text_color=&#8221;#000000&#8243; header_5_font_size=&#8221;38.8px&#8221; custom_margin=&#8221;||3px|||&#8221; header_5_text_align_tablet=&#8221;center&#8221; header_5_text_align_phone=&#8221;center&#8221; header_5_text_align_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div id=\"comp-ld8tkw8e4\" class=\"BaOVQ8 tz5f0K comp-ld8tkw8e4 wixui-rich-text\" data-testid=\"richTextElement\">\n<h5 class=\"font_5 wixui-rich-text__text\">Know Your Mentor<\/h5>\n<\/div>\n<div id=\"comp-ld8tkw8i2\" class=\"BaOVQ8 tz5f0K comp-ld8tkw8i2 wixui-rich-text\" data-testid=\"richTextElement\"><\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Libre Baskerville||||||||&#8221; text_line_height=&#8221;1.9em&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Successfully nailing 1000 projects in the field of architecture in which some of them are awarded for national and international level. Over the course of 20 years of having brilliance expertise, having a vision through developing entrepreneurshi p in the construction industry namely real estate and hospitality creating more employment and nurturing the tourism sector of Maharashtra. With this vision, Kalatrava79.com was born. It will stand as an embodiment providing concepts to completion for all types of projects. These specific projects will cater to the HNI and NRl\u2019s who wish to start a new business in any kind of project ranging from real estate, hospitality, logistics, education, etc \u2013 seeking profitable returns at the comfort of their own homes.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/kalatrava79.com\/wp-content\/uploads\/2023\/05\/1517427413879.jpeg&#8221; title_text=&#8221;1517427413879&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Libre Baskerville||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Libre Baskerville|700|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;38.8px&#8221; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>What you will get<\/h1>\n<div id=\"comp-ld8tn2wc\" class=\"QOX0dS JCRlLH comp-ld8tn2wc-container comp-ld8tn2wc wixui-box\">\n<div id=\"comp-ld8tn2wf\" class=\"BaOVQ8 tz5f0K comp-ld8tn2wf wixui-rich-text\" data-testid=\"richTextElement\">\n<p class=\"font_8 wixui-rich-text__text\">Here\u2019s what you will learn to achieve that goal<\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<p>Strategy for Real Estate<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<p>Core concept of Real Estate<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<p>Branding of Real Estate<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<p>Administration + HR Setup\u00a0<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;-15px||||false|false&#8221; custom_padding=&#8221;0px||0px||true|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<p>Design Matrix with Respect of Sales Concept<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<p>Construction\/PMC<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<h6><span style=\"color: #ffffff;\">QCT <em>(Quality + Commitment + Transformation<\/em><\/span><\/h6>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<p>Marketing For Real Estate<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;100%&#8221; custom_margin=&#8221;-15px||||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<p>Sales for Real Estate<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<h6><span style=\"color: #ffffff;\">\u00a0CRM for Real Estate<\/span><\/h6>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<h6><span style=\"color: #ffffff;\">\u00a0Allied business for Real Estate<\/span><\/h6>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<p>SOP and implementation<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<p>Pre-Development Planning<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb use_icon=&#8221;on&#8221; font_icon=&#8221;&#x5a;||divi||400&#8243; icon_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; icon_placement=&#8221;left&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;1vw|0vw|1vw|1vw|true|false&#8221; border_radii=&#8221;on|4px|4px|4px|4px&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22icon_color%22,%22border_color_all%22%93}&#8221;]<\/p>\n<p>Legal and RERA\u00a0<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_text=&#8221;Get Started&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;gcid-0397d705-8fde-4ce5-86dd-53f31de31eda&#8221; button_bg_enable_image=&#8221;off&#8221; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;RGBA(255,255,255,0)&#8221; button_font=&#8221;Libre Baskerville|700|||||||&#8221; global_colors_info=&#8221;{%22gcid-0397d705-8fde-4ce5-86dd-53f31de31eda%22:%91%22button_bg_color%22%93}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Libre Baskerville||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Libre Baskerville|700|||||||&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;38.8px&#8221; background_enable_color=&#8221;off&#8221; text_orientation=&#8221;center&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<h1>Connect With Us If\u00a0 You Are?<\/h1>\n<div id=\"comp-ld8tn2wc\" class=\"QOX0dS JCRlLH comp-ld8tn2wc-container comp-ld8tn2wc wixui-box\">\n<div id=\"comp-ld8tn2wf\" class=\"BaOVQ8 tz5f0K comp-ld8tn2wf wixui-rich-text\" data-testid=\"richTextElement\">\n<p class=\"font_8 wixui-rich-text__text\">\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Builders&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe0fd;||divi||400&#8243; icon_color=&#8221;gcid-41683ffe-afb2-4f0f-a5e6-9bfed4b559ac&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Libre Baskerville|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; custom_padding=&#8221;3vw||3vw||true|false&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#000000&#8243; global_colors_info=&#8221;{%22gcid-41683ffe-afb2-4f0f-a5e6-9bfed4b559ac%22:%91%22icon_color%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Investors&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe0d8;||divi||400&#8243; icon_color=&#8221;gcid-41683ffe-afb2-4f0f-a5e6-9bfed4b559ac&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Libre Baskerville|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; custom_padding=&#8221;3vw||3vw||true|false&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#000000&#8243; global_colors_info=&#8221;{%22gcid-41683ffe-afb2-4f0f-a5e6-9bfed4b559ac%22:%91%22icon_color%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Students&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf501;||fa||900&#8243; icon_color=&#8221;gcid-41683ffe-afb2-4f0f-a5e6-9bfed4b559ac&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Libre Baskerville|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; custom_padding=&#8221;3vw||3vw||true|false&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#000000&#8243; global_colors_info=&#8221;{%22gcid-41683ffe-afb2-4f0f-a5e6-9bfed4b559ac%22:%91%22icon_color%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Real Estate Consultants &#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf508;||fa||900&#8243; icon_color=&#8221;gcid-41683ffe-afb2-4f0f-a5e6-9bfed4b559ac&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Libre Baskerville|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;14px&#8221; custom_padding=&#8221;3vw||3vw||true|false&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#000000&#8243; global_colors_info=&#8221;{%22gcid-41683ffe-afb2-4f0f-a5e6-9bfed4b559ac%22:%91%22icon_color%22%93}&#8221;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Libre Baskerville||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; header_font=&#8221;Red Hat Text|700|||||||&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;38.8px&#8221; header_5_font=&#8221;Red Hat Text|700|||||||&#8221; header_5_text_color=&#8221;#FFFFFF&#8221; header_5_font_size=&#8221;38.8px&#8221; background_color=&#8221;#000000&#8243; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Training for Design empowerment&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Libre Baskerville|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;24px&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;5.2vw||5.2vw||true|false&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#eebb75&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Customized brief evaluation\/respective case studies\/steps toward mindset development in<br \/>depth<\/p>\n<p>[2 Sessions &#8211; 2 hours Each]<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Training for Coaching + implementation topic with hiring team&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Libre Baskerville|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;20px&#8221; header_line_height=&#8221;1.3em&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;3vw||3vw||true|false&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#eebb75&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Recalling experts\/agencies to work on respective topics externally or setup team and<br \/>implementation of topic<\/p>\n<p>[2 sessions &#8211; 2 hours Each]<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Training for Hand holding &#038; result oriented outcome&#8221; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;Libre Baskerville|700||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;21px&#8221; body_font=&#8221;Libre Baskerville||||||||&#8221; body_text_align=&#8221;center&#8221; body_text_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;4.8vw||4.8vw||true|false&#8221; border_width_all=&#8221;3px&#8221; border_color_all=&#8221;#eebb75&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Actual handholding and analysis to the respective topic and achieving result oriented on<br \/>respective topic with vision<br \/>One to one 4 Session<br \/>[2 Hours Each &#8211; 4 months]<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kalatrava79.com\u00a0Real Estate Surgeon A Comprehensive Program Here\u2019s what you will learn to achieve that goal Know Your Mentor Successfully nailing 1000 projects in the field of architecture in which some of them are awarded for national and international level. Over the course of 20 years of having brilliance expertise, having a vision through developing entrepreneurshi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-30854","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.kalatrava79.com\/index.php\/wp-json\/wp\/v2\/pages\/30854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kalatrava79.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kalatrava79.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kalatrava79.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kalatrava79.com\/index.php\/wp-json\/wp\/v2\/comments?post=30854"}],"version-history":[{"count":75,"href":"https:\/\/www.kalatrava79.com\/index.php\/wp-json\/wp\/v2\/pages\/30854\/revisions"}],"predecessor-version":[{"id":32574,"href":"https:\/\/www.kalatrava79.com\/index.php\/wp-json\/wp\/v2\/pages\/30854\/revisions\/32574"}],"wp:attachment":[{"href":"https:\/\/www.kalatrava79.com\/index.php\/wp-json\/wp\/v2\/media?parent=30854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}